{"id":4597,"date":"2026-05-01T20:49:32","date_gmt":"2026-05-01T20:49:32","guid":{"rendered":"https:\/\/plusdynamique.net\/elearning\/design-thinking-es\/"},"modified":"2026-07-15T15:23:04","modified_gmt":"2026-07-15T15:23:04","slug":"design-thinking-es","status":"publish","type":"elearning","link":"https:\/\/plusdynamique.net\/es\/elearning\/design-thinking-es\/","title":{"rendered":"Design Thinking (ES)"},"content":{"rendered":"<p>\u00bfQu\u00e9 vino antes, el huevo o la gallina? Aunque parece raro, es probable que antes del eso hubiera que preparar varios prototipos; Lo mismo ocurre con el Design Thinking, que basa su funcionamiento en desarrollar prototipos sostenibles para aprender de los errores y desarrollar productos \u00fatiles, atractivos y comercialmente viables;<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 vino antes, el huevo o la gallina? Aunque parece raro, es probable que antes del eso hubiera que preparar varios prototipos; Lo mismo ocurre con el Design Thinking, que basa su funcionamiento en desarrollar prototipos sostenibles para aprender de los errores y desarrollar productos \u00fatiles, atractivos y comercialmente viables;<\/p>","protected":false},"featured_media":0,"template":"","categories":[20],"class_list":["post-4597","elearning","type-elearning","status-publish","hentry","category-business-skills"],"acf":[],"_links":{"self":[{"href":"https:\/\/plusdynamique.net\/es\/wp-json\/wp\/v2\/elearning\/4597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plusdynamique.net\/es\/wp-json\/wp\/v2\/elearning"}],"about":[{"href":"https:\/\/plusdynamique.net\/es\/wp-json\/wp\/v2\/types\/elearning"}],"version-history":[{"count":1,"href":"https:\/\/plusdynamique.net\/es\/wp-json\/wp\/v2\/elearning\/4597\/revisions"}],"predecessor-version":[{"id":9777,"href":"https:\/\/plusdynamique.net\/es\/wp-json\/wp\/v2\/elearning\/4597\/revisions\/9777"}],"wp:attachment":[{"href":"https:\/\/plusdynamique.net\/es\/wp-json\/wp\/v2\/media?parent=4597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plusdynamique.net\/es\/wp-json\/wp\/v2\/categories?post=4597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}