{"id":2734,"date":"2026-05-01T20:16:21","date_gmt":"2026-05-01T20:16:21","guid":{"rendered":"https:\/\/plusdynamique.net\/elearning\/blockchain-pt\/"},"modified":"2026-07-15T15:17:53","modified_gmt":"2026-07-15T15:17:53","slug":"blockchain-pt","status":"publish","type":"elearning","link":"https:\/\/plusdynamique.net\/de\/elearning\/blockchain-pt\/","title":{"rendered":"Blockchain (PT)"},"content":{"rendered":"<p>\u00c9 poss\u00edvel realizar uma transfer\u00eancia online sem que esta seja atrav\u00e9s de um banco?<br \/>\nNeste curso ir\u00e1 aprender tudo o que significa blockchain: seguran\u00e7a, transpar\u00eancia e rapidez.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00c9 poss\u00edvel realizar uma transfer\u00eancia online sem que esta seja atrav\u00e9s de um banco? Neste curso ir\u00e1 aprender tudo o que significa blockchain: seguran\u00e7a, transpar\u00eancia e rapidez.<\/p>","protected":false},"featured_media":0,"template":"","categories":[16],"class_list":["post-2734","elearning","type-elearning","status-publish","hentry","category-technology"],"acf":[],"_links":{"self":[{"href":"https:\/\/plusdynamique.net\/de\/wp-json\/wp\/v2\/elearning\/2734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plusdynamique.net\/de\/wp-json\/wp\/v2\/elearning"}],"about":[{"href":"https:\/\/plusdynamique.net\/de\/wp-json\/wp\/v2\/types\/elearning"}],"version-history":[{"count":1,"href":"https:\/\/plusdynamique.net\/de\/wp-json\/wp\/v2\/elearning\/2734\/revisions"}],"predecessor-version":[{"id":7934,"href":"https:\/\/plusdynamique.net\/de\/wp-json\/wp\/v2\/elearning\/2734\/revisions\/7934"}],"wp:attachment":[{"href":"https:\/\/plusdynamique.net\/de\/wp-json\/wp\/v2\/media?parent=2734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plusdynamique.net\/de\/wp-json\/wp\/v2\/categories?post=2734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}